{"id":6808,"date":"2012-01-04T14:36:00","date_gmt":"2012-01-04T13:36:00","guid":{"rendered":"http:\/\/www.oriolmorte.com\/?p=6808"},"modified":"2016-02-04T03:36:17","modified_gmt":"2016-02-04T02:36:17","slug":"sesion-de-fotos-con-alba-arnau-3","status":"publish","type":"post","link":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/","title":{"rendered":"Sesi\u00f3n de fotos con Alba Arnau"},"content":{"rendered":"<p style=\"text-align: justify;\">Los primeros d\u00edas de verano hice una sesi\u00f3n de fotos con Alba Arnau en el estudio de Moi\u00e0 donde ya pasaron anteriormente Lina Forero, Laia Pons y Vanessa Cots. Hac\u00eda ya 2 o 3 a\u00f1os que hab\u00edamos hablado con Alba de hacer esta sesi\u00f3n y finalmente la materializamos. En la sesi\u00f3n nos acompa\u00f1\u00f3 una buena amiga suya, Mar\u00eda Torres, quien tambien se aventur\u00f3 a coger la c\u00e1mara un rato y tambien hacer de modelo.<\/p>\n<p style=\"text-align: justify;\">La primera parte de la sesi\u00f3n transcurri\u00f3 en el estudio con un set b\u00e1sico de iluminaci\u00f3n y fondo negro. La segunda parte aprovechamos la \u00e9poca del a\u00f1o en la que est\u00e1bamos para hacer unas fotos de exterior en un prado de trigo buscando el \u201clook\u201d de country girl.<\/p>\n<p style=\"text-align: center;\">\u00a0<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-6539\" alt=\"_MG_0009_oriol_morte_blog\" src=\"http:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0009_oriol_morte_blog-710x473.jpg\" width=\"710\" height=\"473\" srcset=\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0009_oriol_morte_blog-710x473.jpg 710w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0009_oriol_morte_blog-600x400.jpg 600w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0009_oriol_morte_blog-899x600.jpg 899w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0009_oriol_morte_blog-705x470.jpg 705w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0009_oriol_morte_blog.jpg 1420w\" sizes=\"(max-width: 710px) 100vw, 710px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-6542\" alt=\"_MG_0187_oriol_morte_blog\" src=\"http:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0187_oriol_morte_blog-400x600.jpg\" width=\"400\" height=\"600\" srcset=\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0187_oriol_morte_blog-400x600.jpg 400w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0187_oriol_morte_blog-600x900.jpg 600w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0187_oriol_morte_blog-470x705.jpg 470w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0187_oriol_morte_blog.jpg 947w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-6545\" alt=\"_MG_0251_oriol_morte_blog\" src=\"http:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0251_oriol_morte_blog-400x600.jpg\" width=\"400\" height=\"600\" srcset=\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0251_oriol_morte_blog-400x600.jpg 400w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0251_oriol_morte_blog-600x900.jpg 600w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0251_oriol_morte_blog-470x705.jpg 470w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0251_oriol_morte_blog.jpg 947w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6548\" alt=\"_MG_0258_oriol_morte_blog\" src=\"http:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0258_oriol_morte_blog-400x600.jpg\" width=\"400\" height=\"600\" srcset=\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0258_oriol_morte_blog-400x600.jpg 400w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0258_oriol_morte_blog-600x900.jpg 600w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0258_oriol_morte_blog-470x705.jpg 470w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0258_oriol_morte_blog.jpg 947w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6551\" alt=\"_MG_0274_oriol_morte_blog\" src=\"http:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_blog-710x473.jpg\" width=\"710\" height=\"473\" srcset=\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_blog-710x473.jpg 710w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_blog-600x400.jpg 600w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_blog-899x600.jpg 899w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_blog-705x470.jpg 705w, https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_blog.jpg 1420w\" sizes=\"(max-width: 710px) 100vw, 710px\" \/><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los primeros d\u00edas de verano hice una sesi\u00f3n de fotos con Alba Arnau en el estudio de Moi\u00e0 donde ya pasaron anteriormente Lina Forero, Laia Pons y Vanessa Cots. Hac\u00eda ya 2 o 3 a\u00f1os que hab\u00edamos hablado con Alba de hacer esta sesi\u00f3n y finalmente la materializamos. En la sesi\u00f3n nos acompa\u00f1\u00f3 una buena amiga suya, Mar\u00eda Torres, quien tambien se aventur\u00f3 a coger la c\u00e1mara un rato y tambien hacer de modelo. La primera parte de la sesi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6556,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[591,331],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sesi\u00f3n de fotos con Alba Arnau - Oriol Morte | Visuals<\/title>\n<meta name=\"description\" content=\"Sessi\u00f3 de fotos d&#039;Alba Arnau i Mar\u00eda Torres en estudi i en exterior en un prat a la primavera\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sesi\u00f3n de fotos con Alba Arnau - Oriol Morte | Visuals\" \/>\n<meta property=\"og:description\" content=\"Sessi\u00f3 de fotos d&#039;Alba Arnau i Mar\u00eda Torres en estudi i en exterior en un prat a la primavera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Oriol Morte | Visuals\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-04T13:36:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-04T02:36:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oriol Morte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oriolmorte\" \/>\n<meta name=\"twitter:site\" content=\"@oriolmorte\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oriol Morte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/\"},\"author\":{\"name\":\"Oriol Morte\",\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/c939f3cb1e4f0e0d005eba682aa7f5a3\"},\"headline\":\"Sesi\u00f3n de fotos con Alba Arnau\",\"datePublished\":\"2012-01-04T13:36:00+00:00\",\"dateModified\":\"2016-02-04T02:36:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/\"},\"wordCount\":142,\"publisher\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/c939f3cb1e4f0e0d005eba682aa7f5a3\"},\"image\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg\",\"keywords\":[\"Alba Arnau\",\"estudi\"],\"articleSection\":[\"Retrat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/\",\"url\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/\",\"name\":\"Sesi\u00f3n de fotos con Alba Arnau - Oriol Morte | Visuals\",\"isPartOf\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg\",\"datePublished\":\"2012-01-04T13:36:00+00:00\",\"dateModified\":\"2016-02-04T02:36:17+00:00\",\"description\":\"Sessi\u00f3 de fotos d'Alba Arnau i Mar\u00eda Torres en estudi i en exterior en un prat a la primavera\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#primaryimage\",\"url\":\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg\",\"contentUrl\":\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oriolmorte.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sesi\u00f3n de fotos con Alba Arnau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/#website\",\"url\":\"https:\/\/www.oriolmorte.com\/ca\/\",\"name\":\"Oriol Morte | Visuals\",\"description\":\"Photography\",\"publisher\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/c939f3cb1e4f0e0d005eba682aa7f5a3\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oriolmorte.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/c939f3cb1e4f0e0d005eba682aa7f5a3\",\"name\":\"Oriol Morte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2014\/03\/logo_OM_black_translucent_background.png\",\"contentUrl\":\"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2014\/03\/logo_OM_black_translucent_background.png\",\"width\":500,\"height\":500,\"caption\":\"Oriol Morte\"},\"logo\":{\"@id\":\"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/image\/\"},\"description\":\"Photographer since 2002\",\"url\":\"https:\/\/www.oriolmorte.com\/ca\/author\/oriolmorte\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sesi\u00f3n de fotos con Alba Arnau - Oriol Morte | Visuals","description":"Sessi\u00f3 de fotos d'Alba Arnau i Mar\u00eda Torres en estudi i en exterior en un prat a la primavera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/","og_locale":"ca_ES","og_type":"article","og_title":"Sesi\u00f3n de fotos con Alba Arnau - Oriol Morte | Visuals","og_description":"Sessi\u00f3 de fotos d'Alba Arnau i Mar\u00eda Torres en estudi i en exterior en un prat a la primavera","og_url":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/","og_site_name":"Oriol Morte | Visuals","article_published_time":"2012-01-04T13:36:00+00:00","article_modified_time":"2016-02-04T02:36:17+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg","type":"image\/jpeg"}],"author":"Oriol Morte","twitter_card":"summary_large_image","twitter_creator":"@oriolmorte","twitter_site":"@oriolmorte","twitter_misc":{"Escrit per":"Oriol Morte","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#article","isPartOf":{"@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/"},"author":{"name":"Oriol Morte","@id":"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/c939f3cb1e4f0e0d005eba682aa7f5a3"},"headline":"Sesi\u00f3n de fotos con Alba Arnau","datePublished":"2012-01-04T13:36:00+00:00","dateModified":"2016-02-04T02:36:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/"},"wordCount":142,"publisher":{"@id":"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/c939f3cb1e4f0e0d005eba682aa7f5a3"},"image":{"@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg","keywords":["Alba Arnau","estudi"],"articleSection":["Retrat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/","url":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/","name":"Sesi\u00f3n de fotos con Alba Arnau - Oriol Morte | Visuals","isPartOf":{"@id":"https:\/\/www.oriolmorte.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#primaryimage"},"image":{"@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg","datePublished":"2012-01-04T13:36:00+00:00","dateModified":"2016-02-04T02:36:17+00:00","description":"Sessi\u00f3 de fotos d'Alba Arnau i Mar\u00eda Torres en estudi i en exterior en un prat a la primavera","breadcrumb":{"@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#primaryimage","url":"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg","contentUrl":"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2012\/01\/MG_0274_oriol_morte_featured_blog-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.oriolmorte.com\/ca\/2012\/01\/04\/sesion-de-fotos-con-alba-arnau-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oriolmorte.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Sesi\u00f3n de fotos con Alba Arnau"}]},{"@type":"WebSite","@id":"https:\/\/www.oriolmorte.com\/ca\/#website","url":"https:\/\/www.oriolmorte.com\/ca\/","name":"Oriol Morte | Visuals","description":"Photography","publisher":{"@id":"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/c939f3cb1e4f0e0d005eba682aa7f5a3"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oriolmorte.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":["Person","Organization"],"@id":"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/c939f3cb1e4f0e0d005eba682aa7f5a3","name":"Oriol Morte","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/image\/","url":"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2014\/03\/logo_OM_black_translucent_background.png","contentUrl":"https:\/\/www.oriolmorte.com\/wp-content\/uploads\/2014\/03\/logo_OM_black_translucent_background.png","width":500,"height":500,"caption":"Oriol Morte"},"logo":{"@id":"https:\/\/www.oriolmorte.com\/ca\/#\/schema\/person\/image\/"},"description":"Photographer since 2002","url":"https:\/\/www.oriolmorte.com\/ca\/author\/oriolmorte\/"}]}},"_links":{"self":[{"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/posts\/6808"}],"collection":[{"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/comments?post=6808"}],"version-history":[{"count":1,"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/posts\/6808\/revisions"}],"predecessor-version":[{"id":6809,"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/posts\/6808\/revisions\/6809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/media\/6556"}],"wp:attachment":[{"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/media?parent=6808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/categories?post=6808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oriolmorte.com\/ca\/wp-json\/wp\/v2\/tags?post=6808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}